{"id":710,"count":10,"description":"","link":"https:\/\/luxclubautos.de\/ru\/model\/ignis\/","name":"Ignis","slug":"ignis","taxonomy":"model","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/model\/710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/model"}],"about":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/taxonomies\/model"}],"wp:post_type":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/auto?model=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}