{"id":574,"count":69,"description":"","link":"https:\/\/luxclubautos.de\/ru\/model\/cullinan\/","name":"Cullinan","slug":"cullinan","taxonomy":"model","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/model\/574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/model"}],"about":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/taxonomies\/model"}],"wp:post_type":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/auto?model=574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}