{"id":184,"count":18,"description":"","link":"https:\/\/luxclubautos.de\/ru\/model\/model-x\/","name":"Model X","slug":"model-x","taxonomy":"model","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/model\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/model"}],"about":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/taxonomies\/model"}],"wp:post_type":[{"href":"https:\/\/luxclubautos.de\/ru\/wp-json\/wp\/v2\/auto?model=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}